{"id":1105,"date":"2015-11-02T13:43:55","date_gmt":"2015-11-02T12:43:55","guid":{"rendered":"https:\/\/calderonbilbao.com\/fr\/biarritz\/"},"modified":"2025-11-06T12:01:30","modified_gmt":"2025-11-06T11:01:30","slug":"biarritz","status":"publish","type":"page","link":"https:\/\/calderonbilbao.com\/fr\/biarritz\/","title":{"rendered":"Biarritz"},"content":{"rendered":"<div id='gallery-1' class='gallery galleryid-1105 gallery-columns-1 gallery-size-large'><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"683\" src=\"https:\/\/calderonbilbao.com\/wp-content\/uploads\/2015\/11\/anglet-01-1024x683.jpg\" class=\"attachment-large size-large\" alt=\"\" srcset=\"https:\/\/calderonbilbao.com\/wp-content\/uploads\/2015\/11\/anglet-01-1024x683.jpg 1024w, https:\/\/calderonbilbao.com\/wp-content\/uploads\/2015\/11\/anglet-01-300x200.jpg 300w, https:\/\/calderonbilbao.com\/wp-content\/uploads\/2015\/11\/anglet-01-768x512.jpg 768w, https:\/\/calderonbilbao.com\/wp-content\/uploads\/2015\/11\/anglet-01-825x550.jpg 825w, https:\/\/calderonbilbao.com\/wp-content\/uploads\/2015\/11\/anglet-01-1200x800.jpg 1200w, https:\/\/calderonbilbao.com\/wp-content\/uploads\/2015\/11\/anglet-01.jpg 1500w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/>\n\t\t\t<\/div><\/figure>\n\t\t<\/div>\n\n<div id='gallery-2' class='gallery galleryid-1105 gallery-columns-2 gallery-size-large'><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon portrait'>\n\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"683\" height=\"1024\" src=\"https:\/\/calderonbilbao.com\/wp-content\/uploads\/2015\/11\/anglet-02-683x1024.jpg\" class=\"attachment-large size-large\" alt=\"\" srcset=\"https:\/\/calderonbilbao.com\/wp-content\/uploads\/2015\/11\/anglet-02-683x1024.jpg 683w, https:\/\/calderonbilbao.com\/wp-content\/uploads\/2015\/11\/anglet-02-200x300.jpg 200w, https:\/\/calderonbilbao.com\/wp-content\/uploads\/2015\/11\/anglet-02-768x1152.jpg 768w, https:\/\/calderonbilbao.com\/wp-content\/uploads\/2015\/11\/anglet-02-533x800.jpg 533w, https:\/\/calderonbilbao.com\/wp-content\/uploads\/2015\/11\/anglet-02.jpg 1000w\" sizes=\"auto, (max-width: 683px) 100vw, 683px\" \/>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon portrait'>\n\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"683\" height=\"1024\" src=\"https:\/\/calderonbilbao.com\/wp-content\/uploads\/2015\/11\/anglet-03-683x1024.jpg\" class=\"attachment-large size-large\" alt=\"\" srcset=\"https:\/\/calderonbilbao.com\/wp-content\/uploads\/2015\/11\/anglet-03-683x1024.jpg 683w, https:\/\/calderonbilbao.com\/wp-content\/uploads\/2015\/11\/anglet-03-200x300.jpg 200w, https:\/\/calderonbilbao.com\/wp-content\/uploads\/2015\/11\/anglet-03-768x1152.jpg 768w, https:\/\/calderonbilbao.com\/wp-content\/uploads\/2015\/11\/anglet-03-533x800.jpg 533w, https:\/\/calderonbilbao.com\/wp-content\/uploads\/2015\/11\/anglet-03.jpg 1000w\" sizes=\"auto, (max-width: 683px) 100vw, 683px\" \/>\n\t\t\t<\/div><\/figure>\n\t\t<\/div>\n\n<div id='gallery-3' class='gallery galleryid-1105 gallery-columns-1 gallery-size-large'><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"683\" src=\"https:\/\/calderonbilbao.com\/wp-content\/uploads\/2015\/11\/anglet-04-1024x683.jpg\" class=\"attachment-large size-large\" alt=\"\" srcset=\"https:\/\/calderonbilbao.com\/wp-content\/uploads\/2015\/11\/anglet-04-1024x683.jpg 1024w, https:\/\/calderonbilbao.com\/wp-content\/uploads\/2015\/11\/anglet-04-300x200.jpg 300w, https:\/\/calderonbilbao.com\/wp-content\/uploads\/2015\/11\/anglet-04-768x512.jpg 768w, https:\/\/calderonbilbao.com\/wp-content\/uploads\/2015\/11\/anglet-04-825x550.jpg 825w, https:\/\/calderonbilbao.com\/wp-content\/uploads\/2015\/11\/anglet-04-1200x800.jpg 1200w, https:\/\/calderonbilbao.com\/wp-content\/uploads\/2015\/11\/anglet-04.jpg 1500w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/>\n\t\t\t<\/div><\/figure>\n\t\t<\/div>\n\n<div id='gallery-4' class='gallery galleryid-1105 gallery-columns-1 gallery-size-large'><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon portrait'>\n\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"683\" height=\"1024\" src=\"https:\/\/calderonbilbao.com\/wp-content\/uploads\/2015\/11\/anglet-05-683x1024.jpg\" class=\"attachment-large size-large\" alt=\"\" srcset=\"https:\/\/calderonbilbao.com\/wp-content\/uploads\/2015\/11\/anglet-05-683x1024.jpg 683w, https:\/\/calderonbilbao.com\/wp-content\/uploads\/2015\/11\/anglet-05-200x300.jpg 200w, https:\/\/calderonbilbao.com\/wp-content\/uploads\/2015\/11\/anglet-05-768x1152.jpg 768w, https:\/\/calderonbilbao.com\/wp-content\/uploads\/2015\/11\/anglet-05-533x800.jpg 533w, https:\/\/calderonbilbao.com\/wp-content\/uploads\/2015\/11\/anglet-05.jpg 1000w\" sizes=\"auto, (max-width: 683px) 100vw, 683px\" \/>\n\t\t\t<\/div><\/figure>\n\t\t<\/div>\n\n<div id='gallery-5' class='gallery galleryid-1105 gallery-columns-1 gallery-size-large'><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon portrait'>\n\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"683\" height=\"1024\" src=\"https:\/\/calderonbilbao.com\/wp-content\/uploads\/2015\/11\/anglet-06-683x1024.jpg\" class=\"attachment-large size-large\" alt=\"\" srcset=\"https:\/\/calderonbilbao.com\/wp-content\/uploads\/2015\/11\/anglet-06-683x1024.jpg 683w, https:\/\/calderonbilbao.com\/wp-content\/uploads\/2015\/11\/anglet-06-200x300.jpg 200w, https:\/\/calderonbilbao.com\/wp-content\/uploads\/2015\/11\/anglet-06-768x1152.jpg 768w, https:\/\/calderonbilbao.com\/wp-content\/uploads\/2015\/11\/anglet-06-533x800.jpg 533w, https:\/\/calderonbilbao.com\/wp-content\/uploads\/2015\/11\/anglet-06.jpg 1000w\" sizes=\"auto, (max-width: 683px) 100vw, 683px\" \/>\n\t\t\t<\/div><\/figure>\n\t\t<\/div>\n\n<div id='gallery-6' class='gallery galleryid-1105 gallery-columns-1 gallery-size-large'><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon portrait'>\n\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"683\" height=\"1024\" src=\"https:\/\/calderonbilbao.com\/wp-content\/uploads\/2015\/11\/anglet-07-683x1024.jpg\" class=\"attachment-large size-large\" alt=\"\" srcset=\"https:\/\/calderonbilbao.com\/wp-content\/uploads\/2015\/11\/anglet-07-683x1024.jpg 683w, https:\/\/calderonbilbao.com\/wp-content\/uploads\/2015\/11\/anglet-07-200x300.jpg 200w, https:\/\/calderonbilbao.com\/wp-content\/uploads\/2015\/11\/anglet-07-768x1152.jpg 768w, https:\/\/calderonbilbao.com\/wp-content\/uploads\/2015\/11\/anglet-07-533x800.jpg 533w, https:\/\/calderonbilbao.com\/wp-content\/uploads\/2015\/11\/anglet-07.jpg 1000w\" sizes=\"auto, (max-width: 683px) 100vw, 683px\" \/>\n\t\t\t<\/div><\/figure>\n\t\t<\/div>\n\n<div id='gallery-7' class='gallery galleryid-1105 gallery-columns-1 gallery-size-large'><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon portrait'>\n\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"683\" height=\"1024\" src=\"https:\/\/calderonbilbao.com\/wp-content\/uploads\/2015\/11\/anglet-08-683x1024.jpg\" class=\"attachment-large size-large\" alt=\"\" srcset=\"https:\/\/calderonbilbao.com\/wp-content\/uploads\/2015\/11\/anglet-08-683x1024.jpg 683w, https:\/\/calderonbilbao.com\/wp-content\/uploads\/2015\/11\/anglet-08-200x300.jpg 200w, https:\/\/calderonbilbao.com\/wp-content\/uploads\/2015\/11\/anglet-08-768x1152.jpg 768w, https:\/\/calderonbilbao.com\/wp-content\/uploads\/2015\/11\/anglet-08-533x800.jpg 533w, https:\/\/calderonbilbao.com\/wp-content\/uploads\/2015\/11\/anglet-08.jpg 1000w\" sizes=\"auto, (max-width: 683px) 100vw, 683px\" \/>\n\t\t\t<\/div><\/figure>\n\t\t<\/div>\n\n<div id='gallery-8' class='gallery galleryid-1105 gallery-columns-1 gallery-size-large'><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon portrait'>\n\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"683\" height=\"1024\" src=\"https:\/\/calderonbilbao.com\/wp-content\/uploads\/2015\/11\/anglet-09-683x1024.jpg\" class=\"attachment-large size-large\" alt=\"\" srcset=\"https:\/\/calderonbilbao.com\/wp-content\/uploads\/2015\/11\/anglet-09-683x1024.jpg 683w, https:\/\/calderonbilbao.com\/wp-content\/uploads\/2015\/11\/anglet-09-200x300.jpg 200w, https:\/\/calderonbilbao.com\/wp-content\/uploads\/2015\/11\/anglet-09-768x1152.jpg 768w, https:\/\/calderonbilbao.com\/wp-content\/uploads\/2015\/11\/anglet-09-533x800.jpg 533w, https:\/\/calderonbilbao.com\/wp-content\/uploads\/2015\/11\/anglet-09.jpg 1000w\" sizes=\"auto, (max-width: 683px) 100vw, 683px\" \/>\n\t\t\t<\/div><\/figure>\n\t\t<\/div>\n\n<div id='gallery-9' class='gallery galleryid-1105 gallery-columns-1 gallery-size-large'><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon portrait'>\n\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"683\" height=\"1024\" src=\"https:\/\/calderonbilbao.com\/wp-content\/uploads\/2015\/11\/anglet-10-683x1024.jpg\" class=\"attachment-large size-large\" alt=\"\" srcset=\"https:\/\/calderonbilbao.com\/wp-content\/uploads\/2015\/11\/anglet-10-683x1024.jpg 683w, https:\/\/calderonbilbao.com\/wp-content\/uploads\/2015\/11\/anglet-10-200x300.jpg 200w, https:\/\/calderonbilbao.com\/wp-content\/uploads\/2015\/11\/anglet-10-768x1152.jpg 768w, https:\/\/calderonbilbao.com\/wp-content\/uploads\/2015\/11\/anglet-10-533x800.jpg 533w, https:\/\/calderonbilbao.com\/wp-content\/uploads\/2015\/11\/anglet-10.jpg 1000w\" sizes=\"auto, (max-width: 683px) 100vw, 683px\" \/>\n\t\t\t<\/div><\/figure>\n\t\t<\/div>\n\n<div id='gallery-10' class='gallery galleryid-1105 gallery-columns-1 gallery-size-large'><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"683\" src=\"https:\/\/calderonbilbao.com\/wp-content\/uploads\/2015\/11\/anglet-11-1024x683.jpg\" class=\"attachment-large size-large\" alt=\"\" srcset=\"https:\/\/calderonbilbao.com\/wp-content\/uploads\/2015\/11\/anglet-11-1024x683.jpg 1024w, https:\/\/calderonbilbao.com\/wp-content\/uploads\/2015\/11\/anglet-11-300x200.jpg 300w, https:\/\/calderonbilbao.com\/wp-content\/uploads\/2015\/11\/anglet-11-768x512.jpg 768w, https:\/\/calderonbilbao.com\/wp-content\/uploads\/2015\/11\/anglet-11-825x550.jpg 825w, https:\/\/calderonbilbao.com\/wp-content\/uploads\/2015\/11\/anglet-11-1200x800.jpg 1200w, https:\/\/calderonbilbao.com\/wp-content\/uploads\/2015\/11\/anglet-11.jpg 1500w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/>\n\t\t\t<\/div><\/figure>\n\t\t<\/div>\n\n<div id='gallery-11' class='gallery galleryid-1105 gallery-columns-1 gallery-size-large'><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon portrait'>\n\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"683\" height=\"1024\" src=\"https:\/\/calderonbilbao.com\/wp-content\/uploads\/2015\/11\/anglet-12-683x1024.jpg\" class=\"attachment-large size-large\" alt=\"\" srcset=\"https:\/\/calderonbilbao.com\/wp-content\/uploads\/2015\/11\/anglet-12-683x1024.jpg 683w, https:\/\/calderonbilbao.com\/wp-content\/uploads\/2015\/11\/anglet-12-200x300.jpg 200w, https:\/\/calderonbilbao.com\/wp-content\/uploads\/2015\/11\/anglet-12-768x1152.jpg 768w, https:\/\/calderonbilbao.com\/wp-content\/uploads\/2015\/11\/anglet-12-533x800.jpg 533w, https:\/\/calderonbilbao.com\/wp-content\/uploads\/2015\/11\/anglet-12.jpg 1000w\" sizes=\"auto, (max-width: 683px) 100vw, 683px\" \/>\n\t\t\t<\/div><\/figure>\n\t\t<\/div>\n\n<div id='gallery-12' class='gallery galleryid-1105 gallery-columns-1 gallery-size-large'><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"685\" src=\"https:\/\/calderonbilbao.com\/wp-content\/uploads\/2015\/11\/anglet-13-1024x685.jpg\" class=\"attachment-large size-large\" alt=\"\" srcset=\"https:\/\/calderonbilbao.com\/wp-content\/uploads\/2015\/11\/anglet-13-1024x685.jpg 1024w, https:\/\/calderonbilbao.com\/wp-content\/uploads\/2015\/11\/anglet-13-300x201.jpg 300w, https:\/\/calderonbilbao.com\/wp-content\/uploads\/2015\/11\/anglet-13-768x514.jpg 768w, https:\/\/calderonbilbao.com\/wp-content\/uploads\/2015\/11\/anglet-13-1196x800.jpg 1196w, https:\/\/calderonbilbao.com\/wp-content\/uploads\/2015\/11\/anglet-13.jpg 1500w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/>\n\t\t\t<\/div><\/figure>\n\t\t<\/div>\n\n<div id='gallery-13' class='gallery galleryid-1105 gallery-columns-1 gallery-size-large'><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon portrait'>\n\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"683\" height=\"1024\" src=\"https:\/\/calderonbilbao.com\/wp-content\/uploads\/2015\/11\/anglet-14-683x1024.jpg\" class=\"attachment-large size-large\" alt=\"\" srcset=\"https:\/\/calderonbilbao.com\/wp-content\/uploads\/2015\/11\/anglet-14-683x1024.jpg 683w, https:\/\/calderonbilbao.com\/wp-content\/uploads\/2015\/11\/anglet-14-200x300.jpg 200w, https:\/\/calderonbilbao.com\/wp-content\/uploads\/2015\/11\/anglet-14-768x1152.jpg 768w, https:\/\/calderonbilbao.com\/wp-content\/uploads\/2015\/11\/anglet-14-533x800.jpg 533w, https:\/\/calderonbilbao.com\/wp-content\/uploads\/2015\/11\/anglet-14.jpg 1000w\" sizes=\"auto, (max-width: 683px) 100vw, 683px\" \/>\n\t\t\t<\/div><\/figure>\n\t\t<\/div>\n\n<div id='gallery-14' class='gallery galleryid-1105 gallery-columns-1 gallery-size-large'><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"683\" src=\"https:\/\/calderonbilbao.com\/wp-content\/uploads\/2015\/11\/anglet-15-1024x683.jpg\" class=\"attachment-large size-large\" alt=\"\" srcset=\"https:\/\/calderonbilbao.com\/wp-content\/uploads\/2015\/11\/anglet-15-1024x683.jpg 1024w, https:\/\/calderonbilbao.com\/wp-content\/uploads\/2015\/11\/anglet-15-300x200.jpg 300w, https:\/\/calderonbilbao.com\/wp-content\/uploads\/2015\/11\/anglet-15-768x512.jpg 768w, https:\/\/calderonbilbao.com\/wp-content\/uploads\/2015\/11\/anglet-15-825x550.jpg 825w, https:\/\/calderonbilbao.com\/wp-content\/uploads\/2015\/11\/anglet-15-1200x800.jpg 1200w, https:\/\/calderonbilbao.com\/wp-content\/uploads\/2015\/11\/anglet-15.jpg 1500w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/>\n\t\t\t<\/div><\/figure>\n\t\t<\/div>\n\n<div id='gallery-15' class='gallery galleryid-1105 gallery-columns-1 gallery-size-large'><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon portrait'>\n\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"683\" height=\"1024\" src=\"https:\/\/calderonbilbao.com\/wp-content\/uploads\/2015\/11\/anglet-16-683x1024.jpg\" class=\"attachment-large size-large\" alt=\"\" srcset=\"https:\/\/calderonbilbao.com\/wp-content\/uploads\/2015\/11\/anglet-16-683x1024.jpg 683w, https:\/\/calderonbilbao.com\/wp-content\/uploads\/2015\/11\/anglet-16-200x300.jpg 200w, https:\/\/calderonbilbao.com\/wp-content\/uploads\/2015\/11\/anglet-16-768x1152.jpg 768w, https:\/\/calderonbilbao.com\/wp-content\/uploads\/2015\/11\/anglet-16-533x800.jpg 533w, https:\/\/calderonbilbao.com\/wp-content\/uploads\/2015\/11\/anglet-16.jpg 1000w\" sizes=\"auto, (max-width: 683px) 100vw, 683px\" \/>\n\t\t\t<\/div><\/figure>\n\t\t<\/div>\n\n<div id='gallery-16' class='gallery galleryid-1105 gallery-columns-1 gallery-size-large'><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon portrait'>\n\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"683\" height=\"1024\" src=\"https:\/\/calderonbilbao.com\/wp-content\/uploads\/2015\/11\/anglet-17-683x1024.jpg\" class=\"attachment-large size-large\" alt=\"\" srcset=\"https:\/\/calderonbilbao.com\/wp-content\/uploads\/2015\/11\/anglet-17-683x1024.jpg 683w, https:\/\/calderonbilbao.com\/wp-content\/uploads\/2015\/11\/anglet-17-200x300.jpg 200w, https:\/\/calderonbilbao.com\/wp-content\/uploads\/2015\/11\/anglet-17-768x1152.jpg 768w, https:\/\/calderonbilbao.com\/wp-content\/uploads\/2015\/11\/anglet-17-533x800.jpg 533w, https:\/\/calderonbilbao.com\/wp-content\/uploads\/2015\/11\/anglet-17.jpg 1000w\" sizes=\"auto, (max-width: 683px) 100vw, 683px\" \/>\n\t\t\t<\/div><\/figure>\n\t\t<\/div>\n\n<div id='gallery-17' class='gallery galleryid-1105 gallery-columns-1 gallery-size-large'><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"683\" src=\"https:\/\/calderonbilbao.com\/wp-content\/uploads\/2015\/11\/anglet-18-1024x683.jpg\" class=\"attachment-large size-large\" alt=\"\" srcset=\"https:\/\/calderonbilbao.com\/wp-content\/uploads\/2015\/11\/anglet-18-1024x683.jpg 1024w, https:\/\/calderonbilbao.com\/wp-content\/uploads\/2015\/11\/anglet-18-300x200.jpg 300w, https:\/\/calderonbilbao.com\/wp-content\/uploads\/2015\/11\/anglet-18-768x512.jpg 768w, https:\/\/calderonbilbao.com\/wp-content\/uploads\/2015\/11\/anglet-18-825x550.jpg 825w, https:\/\/calderonbilbao.com\/wp-content\/uploads\/2015\/11\/anglet-18-1200x800.jpg 1200w, https:\/\/calderonbilbao.com\/wp-content\/uploads\/2015\/11\/anglet-18.jpg 1500w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/>\n\t\t\t<\/div><\/figure>\n\t\t<\/div>\n\n<div id='gallery-18' class='gallery galleryid-1105 gallery-columns-2 gallery-size-large'><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"683\" src=\"https:\/\/calderonbilbao.com\/wp-content\/uploads\/2015\/11\/anglet-19-1024x683.jpg\" class=\"attachment-large size-large\" alt=\"\" srcset=\"https:\/\/calderonbilbao.com\/wp-content\/uploads\/2015\/11\/anglet-19-1024x683.jpg 1024w, https:\/\/calderonbilbao.com\/wp-content\/uploads\/2015\/11\/anglet-19-300x200.jpg 300w, https:\/\/calderonbilbao.com\/wp-content\/uploads\/2015\/11\/anglet-19-768x512.jpg 768w, https:\/\/calderonbilbao.com\/wp-content\/uploads\/2015\/11\/anglet-19-825x550.jpg 825w, https:\/\/calderonbilbao.com\/wp-content\/uploads\/2015\/11\/anglet-19-1200x800.jpg 1200w, https:\/\/calderonbilbao.com\/wp-content\/uploads\/2015\/11\/anglet-19.jpg 1500w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"683\" src=\"https:\/\/calderonbilbao.com\/wp-content\/uploads\/2015\/11\/anglet-20-1024x683.jpg\" class=\"attachment-large size-large\" alt=\"\" srcset=\"https:\/\/calderonbilbao.com\/wp-content\/uploads\/2015\/11\/anglet-20-1024x683.jpg 1024w, https:\/\/calderonbilbao.com\/wp-content\/uploads\/2015\/11\/anglet-20-300x200.jpg 300w, https:\/\/calderonbilbao.com\/wp-content\/uploads\/2015\/11\/anglet-20-768x512.jpg 768w, https:\/\/calderonbilbao.com\/wp-content\/uploads\/2015\/11\/anglet-20-825x550.jpg 825w, https:\/\/calderonbilbao.com\/wp-content\/uploads\/2015\/11\/anglet-20-1200x800.jpg 1200w, https:\/\/calderonbilbao.com\/wp-content\/uploads\/2015\/11\/anglet-20.jpg 1500w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/>\n\t\t\t<\/div><\/figure>\n\t\t<\/div>\n\n<div id='gallery-19' class='gallery galleryid-1105 gallery-columns-1 gallery-size-large'><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"683\" src=\"https:\/\/calderonbilbao.com\/wp-content\/uploads\/2015\/11\/anglet-21-1024x683.jpg\" class=\"attachment-large size-large\" alt=\"\" srcset=\"https:\/\/calderonbilbao.com\/wp-content\/uploads\/2015\/11\/anglet-21-1024x683.jpg 1024w, https:\/\/calderonbilbao.com\/wp-content\/uploads\/2015\/11\/anglet-21-300x200.jpg 300w, https:\/\/calderonbilbao.com\/wp-content\/uploads\/2015\/11\/anglet-21-768x512.jpg 768w, https:\/\/calderonbilbao.com\/wp-content\/uploads\/2015\/11\/anglet-21-825x550.jpg 825w, https:\/\/calderonbilbao.com\/wp-content\/uploads\/2015\/11\/anglet-21-1200x800.jpg 1200w, https:\/\/calderonbilbao.com\/wp-content\/uploads\/2015\/11\/anglet-21.jpg 1500w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/>\n\t\t\t<\/div><\/figure>\n\t\t<\/div>\n\n<div id='gallery-20' class='gallery galleryid-1105 gallery-columns-1 gallery-size-large'><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon portrait'>\n\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"683\" height=\"1024\" src=\"https:\/\/calderonbilbao.com\/wp-content\/uploads\/2015\/11\/anglet-22-683x1024.jpg\" class=\"attachment-large size-large\" alt=\"\" srcset=\"https:\/\/calderonbilbao.com\/wp-content\/uploads\/2015\/11\/anglet-22-683x1024.jpg 683w, https:\/\/calderonbilbao.com\/wp-content\/uploads\/2015\/11\/anglet-22-200x300.jpg 200w, https:\/\/calderonbilbao.com\/wp-content\/uploads\/2015\/11\/anglet-22-768x1152.jpg 768w, https:\/\/calderonbilbao.com\/wp-content\/uploads\/2015\/11\/anglet-22-533x800.jpg 533w, https:\/\/calderonbilbao.com\/wp-content\/uploads\/2015\/11\/anglet-22.jpg 1000w\" sizes=\"auto, (max-width: 683px) 100vw, 683px\" \/>\n\t\t\t<\/div><\/figure>\n\t\t<\/div>\n\n<div id='gallery-21' class='gallery galleryid-1105 gallery-columns-1 gallery-size-large'><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon portrait'>\n\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"683\" height=\"1024\" src=\"https:\/\/calderonbilbao.com\/wp-content\/uploads\/2015\/11\/anglet-23-683x1024.jpg\" class=\"attachment-large size-large\" alt=\"\" srcset=\"https:\/\/calderonbilbao.com\/wp-content\/uploads\/2015\/11\/anglet-23-683x1024.jpg 683w, https:\/\/calderonbilbao.com\/wp-content\/uploads\/2015\/11\/anglet-23-200x300.jpg 200w, https:\/\/calderonbilbao.com\/wp-content\/uploads\/2015\/11\/anglet-23-768x1152.jpg 768w, https:\/\/calderonbilbao.com\/wp-content\/uploads\/2015\/11\/anglet-23-533x800.jpg 533w, https:\/\/calderonbilbao.com\/wp-content\/uploads\/2015\/11\/anglet-23.jpg 1000w\" sizes=\"auto, (max-width: 683px) 100vw, 683px\" \/>\n\t\t\t<\/div><\/figure>\n\t\t<\/div>\n\n<div id='gallery-22' class='gallery galleryid-1105 gallery-columns-1 gallery-size-large'><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon portrait'>\n\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"683\" height=\"1024\" src=\"https:\/\/calderonbilbao.com\/wp-content\/uploads\/2015\/11\/anglet-24-683x1024.jpg\" class=\"attachment-large size-large\" alt=\"\" srcset=\"https:\/\/calderonbilbao.com\/wp-content\/uploads\/2015\/11\/anglet-24-683x1024.jpg 683w, https:\/\/calderonbilbao.com\/wp-content\/uploads\/2015\/11\/anglet-24-200x300.jpg 200w, https:\/\/calderonbilbao.com\/wp-content\/uploads\/2015\/11\/anglet-24-768x1152.jpg 768w, https:\/\/calderonbilbao.com\/wp-content\/uploads\/2015\/11\/anglet-24-533x800.jpg 533w, https:\/\/calderonbilbao.com\/wp-content\/uploads\/2015\/11\/anglet-24.jpg 1000w\" sizes=\"auto, (max-width: 683px) 100vw, 683px\" \/>\n\t\t\t<\/div><\/figure>\n\t\t<\/div>\n\n<div id='gallery-23' class='gallery galleryid-1105 gallery-columns-1 gallery-size-large'><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"683\" src=\"https:\/\/calderonbilbao.com\/wp-content\/uploads\/2015\/11\/anglet-25-1024x683.jpg\" class=\"attachment-large size-large\" alt=\"\" srcset=\"https:\/\/calderonbilbao.com\/wp-content\/uploads\/2015\/11\/anglet-25-1024x683.jpg 1024w, https:\/\/calderonbilbao.com\/wp-content\/uploads\/2015\/11\/anglet-25-300x200.jpg 300w, https:\/\/calderonbilbao.com\/wp-content\/uploads\/2015\/11\/anglet-25-768x512.jpg 768w, https:\/\/calderonbilbao.com\/wp-content\/uploads\/2015\/11\/anglet-25-825x550.jpg 825w, https:\/\/calderonbilbao.com\/wp-content\/uploads\/2015\/11\/anglet-25-1200x800.jpg 1200w, https:\/\/calderonbilbao.com\/wp-content\/uploads\/2015\/11\/anglet-25.jpg 1500w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/>\n\t\t\t<\/div><\/figure>\n\t\t<\/div>\n\n<div id='gallery-24' class='gallery galleryid-1105 gallery-columns-1 gallery-size-large'><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon portrait'>\n\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"683\" height=\"1024\" src=\"https:\/\/calderonbilbao.com\/wp-content\/uploads\/2015\/11\/anglet-26-683x1024.jpg\" class=\"attachment-large size-large\" alt=\"\" srcset=\"https:\/\/calderonbilbao.com\/wp-content\/uploads\/2015\/11\/anglet-26-683x1024.jpg 683w, https:\/\/calderonbilbao.com\/wp-content\/uploads\/2015\/11\/anglet-26-200x300.jpg 200w, https:\/\/calderonbilbao.com\/wp-content\/uploads\/2015\/11\/anglet-26-768x1152.jpg 768w, https:\/\/calderonbilbao.com\/wp-content\/uploads\/2015\/11\/anglet-26-533x800.jpg 533w, https:\/\/calderonbilbao.com\/wp-content\/uploads\/2015\/11\/anglet-26.jpg 1000w\" sizes=\"auto, (max-width: 683px) 100vw, 683px\" \/>\n\t\t\t<\/div><\/figure>\n\t\t<\/div>\n\n<div id='gallery-25' class='gallery galleryid-1105 gallery-columns-1 gallery-size-large'><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"683\" src=\"https:\/\/calderonbilbao.com\/wp-content\/uploads\/2015\/11\/anglet-27-1024x683.jpg\" class=\"attachment-large size-large\" alt=\"\" srcset=\"https:\/\/calderonbilbao.com\/wp-content\/uploads\/2015\/11\/anglet-27-1024x683.jpg 1024w, https:\/\/calderonbilbao.com\/wp-content\/uploads\/2015\/11\/anglet-27-300x200.jpg 300w, https:\/\/calderonbilbao.com\/wp-content\/uploads\/2015\/11\/anglet-27-768x512.jpg 768w, https:\/\/calderonbilbao.com\/wp-content\/uploads\/2015\/11\/anglet-27-825x550.jpg 825w, https:\/\/calderonbilbao.com\/wp-content\/uploads\/2015\/11\/anglet-27-1200x800.jpg 1200w, https:\/\/calderonbilbao.com\/wp-content\/uploads\/2015\/11\/anglet-27.jpg 1500w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/>\n\t\t\t<\/div><\/figure>\n\t\t<\/div>\n\n<div id='gallery-26' class='gallery galleryid-1105 gallery-columns-1 gallery-size-large'><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"683\" src=\"https:\/\/calderonbilbao.com\/wp-content\/uploads\/2015\/11\/anglet-28-1024x683.jpg\" class=\"attachment-large size-large\" alt=\"\" srcset=\"https:\/\/calderonbilbao.com\/wp-content\/uploads\/2015\/11\/anglet-28-1024x683.jpg 1024w, https:\/\/calderonbilbao.com\/wp-content\/uploads\/2015\/11\/anglet-28-300x200.jpg 300w, https:\/\/calderonbilbao.com\/wp-content\/uploads\/2015\/11\/anglet-28-768x512.jpg 768w, https:\/\/calderonbilbao.com\/wp-content\/uploads\/2015\/11\/anglet-28-825x550.jpg 825w, https:\/\/calderonbilbao.com\/wp-content\/uploads\/2015\/11\/anglet-28-1200x800.jpg 1200w, https:\/\/calderonbilbao.com\/wp-content\/uploads\/2015\/11\/anglet-28.jpg 1500w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/>\n\t\t\t<\/div><\/figure>\n\t\t<\/div>\n\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":1,"featured_media":536,"parent":0,"menu_order":20,"comment_status":"closed","ping_status":"closed","template":"page-horizontal.php","meta":{"footnotes":""},"class_list":["post-1105","page","type-page","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Biarritz - Calder\u00f3n Bilbao<\/title>\n<meta name=\"description\" content=\"Rehabilitaci\u00f3n y decoraci\u00f3n integral realizada por Cristina y Ana Calder\u00f3n de una villa en Biarritz con vistas al mar. Vivienda de verano de una familia parisina.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/calderonbilbao.com\/fr\/biarritz\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Biarritz - Calder\u00f3n Bilbao\" \/>\n<meta property=\"og:description\" content=\"Rehabilitaci\u00f3n y decoraci\u00f3n integral realizada por Cristina y Ana Calder\u00f3n de una villa en Biarritz con vistas al mar. Vivienda de verano de una familia parisina.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/calderonbilbao.com\/fr\/biarritz\/\" \/>\n<meta property=\"og:site_name\" content=\"Calder\u00f3n Bilbao\" \/>\n<meta property=\"article:modified_time\" content=\"2025-11-06T11:01:30+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/calderonbilbao.com\/wp-content\/uploads\/2015\/11\/anglet-01.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1500\" \/>\n\t<meta property=\"og:image:height\" content=\"1000\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/calderonbilbao.com\\\/fr\\\/biarritz\\\/\",\"url\":\"https:\\\/\\\/calderonbilbao.com\\\/fr\\\/biarritz\\\/\",\"name\":\"Biarritz - Calder\u00f3n Bilbao\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/calderonbilbao.com\\\/fr\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/calderonbilbao.com\\\/fr\\\/biarritz\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/calderonbilbao.com\\\/fr\\\/biarritz\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/calderonbilbao.com\\\/wp-content\\\/uploads\\\/2015\\\/11\\\/anglet-01.jpg\",\"datePublished\":\"2015-11-02T12:43:55+00:00\",\"dateModified\":\"2025-11-06T11:01:30+00:00\",\"description\":\"Rehabilitaci\u00f3n y decoraci\u00f3n integral realizada por Cristina y Ana Calder\u00f3n de una villa en Biarritz con vistas al mar. Vivienda de verano de una familia parisina.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/calderonbilbao.com\\\/fr\\\/biarritz\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/calderonbilbao.com\\\/fr\\\/biarritz\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/calderonbilbao.com\\\/fr\\\/biarritz\\\/#primaryimage\",\"url\":\"https:\\\/\\\/calderonbilbao.com\\\/wp-content\\\/uploads\\\/2015\\\/11\\\/anglet-01.jpg\",\"contentUrl\":\"https:\\\/\\\/calderonbilbao.com\\\/wp-content\\\/uploads\\\/2015\\\/11\\\/anglet-01.jpg\",\"width\":1500,\"height\":1000},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/calderonbilbao.com\\\/fr\\\/biarritz\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/calderonbilbao.com\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Biarritz\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/calderonbilbao.com\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/calderonbilbao.com\\\/fr\\\/\",\"name\":\"Calder\u00f3n Bilbao\",\"description\":\"Decoraci\u00f3n\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/calderonbilbao.com\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Biarritz - Calder\u00f3n Bilbao","description":"Rehabilitaci\u00f3n y decoraci\u00f3n integral realizada por Cristina y Ana Calder\u00f3n de una villa en Biarritz con vistas al mar. Vivienda de verano de una familia parisina.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/calderonbilbao.com\/fr\/biarritz\/","og_locale":"fr_FR","og_type":"article","og_title":"Biarritz - Calder\u00f3n Bilbao","og_description":"Rehabilitaci\u00f3n y decoraci\u00f3n integral realizada por Cristina y Ana Calder\u00f3n de una villa en Biarritz con vistas al mar. Vivienda de verano de una familia parisina.","og_url":"https:\/\/calderonbilbao.com\/fr\/biarritz\/","og_site_name":"Calder\u00f3n Bilbao","article_modified_time":"2025-11-06T11:01:30+00:00","og_image":[{"width":1500,"height":1000,"url":"https:\/\/calderonbilbao.com\/wp-content\/uploads\/2015\/11\/anglet-01.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Dur\u00e9e de lecture estim\u00e9e":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/calderonbilbao.com\/fr\/biarritz\/","url":"https:\/\/calderonbilbao.com\/fr\/biarritz\/","name":"Biarritz - Calder\u00f3n Bilbao","isPartOf":{"@id":"https:\/\/calderonbilbao.com\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/calderonbilbao.com\/fr\/biarritz\/#primaryimage"},"image":{"@id":"https:\/\/calderonbilbao.com\/fr\/biarritz\/#primaryimage"},"thumbnailUrl":"https:\/\/calderonbilbao.com\/wp-content\/uploads\/2015\/11\/anglet-01.jpg","datePublished":"2015-11-02T12:43:55+00:00","dateModified":"2025-11-06T11:01:30+00:00","description":"Rehabilitaci\u00f3n y decoraci\u00f3n integral realizada por Cristina y Ana Calder\u00f3n de una villa en Biarritz con vistas al mar. Vivienda de verano de una familia parisina.","breadcrumb":{"@id":"https:\/\/calderonbilbao.com\/fr\/biarritz\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/calderonbilbao.com\/fr\/biarritz\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/calderonbilbao.com\/fr\/biarritz\/#primaryimage","url":"https:\/\/calderonbilbao.com\/wp-content\/uploads\/2015\/11\/anglet-01.jpg","contentUrl":"https:\/\/calderonbilbao.com\/wp-content\/uploads\/2015\/11\/anglet-01.jpg","width":1500,"height":1000},{"@type":"BreadcrumbList","@id":"https:\/\/calderonbilbao.com\/fr\/biarritz\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/calderonbilbao.com\/fr\/"},{"@type":"ListItem","position":2,"name":"Biarritz"}]},{"@type":"WebSite","@id":"https:\/\/calderonbilbao.com\/fr\/#website","url":"https:\/\/calderonbilbao.com\/fr\/","name":"Calder\u00f3n Bilbao","description":"Decoraci\u00f3n","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/calderonbilbao.com\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"}]}},"_links":{"self":[{"href":"https:\/\/calderonbilbao.com\/fr\/wp-json\/wp\/v2\/pages\/1105","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/calderonbilbao.com\/fr\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/calderonbilbao.com\/fr\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/calderonbilbao.com\/fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/calderonbilbao.com\/fr\/wp-json\/wp\/v2\/comments?post=1105"}],"version-history":[{"count":1,"href":"https:\/\/calderonbilbao.com\/fr\/wp-json\/wp\/v2\/pages\/1105\/revisions"}],"predecessor-version":[{"id":1113,"href":"https:\/\/calderonbilbao.com\/fr\/wp-json\/wp\/v2\/pages\/1105\/revisions\/1113"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/calderonbilbao.com\/fr\/wp-json\/wp\/v2\/media\/536"}],"wp:attachment":[{"href":"https:\/\/calderonbilbao.com\/fr\/wp-json\/wp\/v2\/media?parent=1105"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}