{"id":1134,"date":"2015-11-25T10:46:56","date_gmt":"2015-11-25T09:46:56","guid":{"rendered":"http:\/\/calderonbilbao.com\/en\/aravaca\/"},"modified":"2025-11-06T12:02:14","modified_gmt":"2025-11-06T11:02:14","slug":"aravaca","status":"publish","type":"page","link":"https:\/\/calderonbilbao.com\/en\/aravaca\/","title":{"rendered":"Aravaca"},"content":{"rendered":"<div id='gallery-1' class='gallery galleryid-1134 gallery-columns-1 gallery-size-large'><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"681\" src=\"https:\/\/calderonbilbao.com\/wp-content\/uploads\/2015\/11\/aravaca-01-1024x681.jpg\" class=\"attachment-large size-large\" alt=\"\" srcset=\"https:\/\/calderonbilbao.com\/wp-content\/uploads\/2015\/11\/aravaca-01-1024x681.jpg 1024w, https:\/\/calderonbilbao.com\/wp-content\/uploads\/2015\/11\/aravaca-01-300x200.jpg 300w, https:\/\/calderonbilbao.com\/wp-content\/uploads\/2015\/11\/aravaca-01-768x511.jpg 768w, https:\/\/calderonbilbao.com\/wp-content\/uploads\/2015\/11\/aravaca-01-825x550.jpg 825w, https:\/\/calderonbilbao.com\/wp-content\/uploads\/2015\/11\/aravaca-01-1200x798.jpg 1200w, https:\/\/calderonbilbao.com\/wp-content\/uploads\/2015\/11\/aravaca-01.jpg 1500w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/>\n\t\t\t<\/div><\/figure>\n\t\t<\/div>\n\n<div id='gallery-2' class='gallery galleryid-1134 gallery-columns-2 gallery-size-large'><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon portrait'>\n\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"488\" height=\"612\" src=\"https:\/\/calderonbilbao.com\/wp-content\/uploads\/2015\/11\/aravaca-02.jpg\" class=\"attachment-large size-large\" alt=\"\" srcset=\"https:\/\/calderonbilbao.com\/wp-content\/uploads\/2015\/11\/aravaca-02.jpg 488w, https:\/\/calderonbilbao.com\/wp-content\/uploads\/2015\/11\/aravaca-02-239x300.jpg 239w\" sizes=\"auto, (max-width: 488px) 100vw, 488px\" \/>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon portrait'>\n\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"612\" height=\"768\" src=\"https:\/\/calderonbilbao.com\/wp-content\/uploads\/2015\/11\/aravaca-03.jpg\" class=\"attachment-large size-large\" alt=\"\" srcset=\"https:\/\/calderonbilbao.com\/wp-content\/uploads\/2015\/11\/aravaca-03.jpg 612w, https:\/\/calderonbilbao.com\/wp-content\/uploads\/2015\/11\/aravaca-03-239x300.jpg 239w\" sizes=\"auto, (max-width: 612px) 100vw, 612px\" \/>\n\t\t\t<\/div><\/figure>\n\t\t<\/div>\n\n<div id='gallery-3' class='gallery galleryid-1134 gallery-columns-2 gallery-size-large'><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon portrait'>\n\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"612\" height=\"768\" src=\"https:\/\/calderonbilbao.com\/wp-content\/uploads\/2015\/11\/aravaca-04.jpg\" class=\"attachment-large size-large\" alt=\"\" srcset=\"https:\/\/calderonbilbao.com\/wp-content\/uploads\/2015\/11\/aravaca-04.jpg 612w, https:\/\/calderonbilbao.com\/wp-content\/uploads\/2015\/11\/aravaca-04-239x300.jpg 239w\" sizes=\"auto, (max-width: 612px) 100vw, 612px\" \/>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon portrait'>\n\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"612\" height=\"768\" src=\"https:\/\/calderonbilbao.com\/wp-content\/uploads\/2015\/11\/aravaca-05.jpg\" class=\"attachment-large size-large\" alt=\"\" srcset=\"https:\/\/calderonbilbao.com\/wp-content\/uploads\/2015\/11\/aravaca-05.jpg 612w, https:\/\/calderonbilbao.com\/wp-content\/uploads\/2015\/11\/aravaca-05-239x300.jpg 239w\" sizes=\"auto, (max-width: 612px) 100vw, 612px\" \/>\n\t\t\t<\/div><\/figure>\n\t\t<\/div>\n\n<div id='gallery-4' class='gallery galleryid-1134 gallery-columns-2 gallery-size-large'><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"768\" height=\"511\" src=\"https:\/\/calderonbilbao.com\/wp-content\/uploads\/2015\/11\/aravaca-06.jpg\" class=\"attachment-large size-large\" alt=\"\" srcset=\"https:\/\/calderonbilbao.com\/wp-content\/uploads\/2015\/11\/aravaca-06.jpg 768w, https:\/\/calderonbilbao.com\/wp-content\/uploads\/2015\/11\/aravaca-06-300x200.jpg 300w\" sizes=\"auto, (max-width: 768px) 100vw, 768px\" \/>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"768\" height=\"511\" src=\"https:\/\/calderonbilbao.com\/wp-content\/uploads\/2015\/11\/aravaca-07.jpg\" class=\"attachment-large size-large\" alt=\"\" srcset=\"https:\/\/calderonbilbao.com\/wp-content\/uploads\/2015\/11\/aravaca-07.jpg 768w, https:\/\/calderonbilbao.com\/wp-content\/uploads\/2015\/11\/aravaca-07-300x200.jpg 300w\" sizes=\"auto, (max-width: 768px) 100vw, 768px\" \/>\n\t\t\t<\/div><\/figure>\n\t\t<\/div>\n\n<div id='gallery-5' class='gallery galleryid-1134 gallery-columns-2 gallery-size-large'><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon portrait'>\n\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"511\" height=\"768\" src=\"https:\/\/calderonbilbao.com\/wp-content\/uploads\/2015\/11\/aravaca-08.jpg\" class=\"attachment-large size-large\" alt=\"\" srcset=\"https:\/\/calderonbilbao.com\/wp-content\/uploads\/2015\/11\/aravaca-08.jpg 511w, https:\/\/calderonbilbao.com\/wp-content\/uploads\/2015\/11\/aravaca-08-200x300.jpg 200w\" sizes=\"auto, (max-width: 511px) 100vw, 511px\" \/>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon portrait'>\n\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"511\" height=\"768\" src=\"https:\/\/calderonbilbao.com\/wp-content\/uploads\/2015\/11\/aravaca-09.jpg\" class=\"attachment-large size-large\" alt=\"\" srcset=\"https:\/\/calderonbilbao.com\/wp-content\/uploads\/2015\/11\/aravaca-09.jpg 511w, https:\/\/calderonbilbao.com\/wp-content\/uploads\/2015\/11\/aravaca-09-200x300.jpg 200w\" sizes=\"auto, (max-width: 511px) 100vw, 511px\" \/>\n\t\t\t<\/div><\/figure>\n\t\t<\/div>\n\n<div id='gallery-6' class='gallery galleryid-1134 gallery-columns-2 gallery-size-large'><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"612\" height=\"612\" src=\"https:\/\/calderonbilbao.com\/wp-content\/uploads\/2015\/11\/aravaca-10.jpg\" class=\"attachment-large size-large\" alt=\"\" srcset=\"https:\/\/calderonbilbao.com\/wp-content\/uploads\/2015\/11\/aravaca-10.jpg 612w, https:\/\/calderonbilbao.com\/wp-content\/uploads\/2015\/11\/aravaca-10-150x150.jpg 150w, https:\/\/calderonbilbao.com\/wp-content\/uploads\/2015\/11\/aravaca-10-300x300.jpg 300w\" sizes=\"auto, (max-width: 612px) 100vw, 612px\" \/>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"612\" height=\"612\" src=\"https:\/\/calderonbilbao.com\/wp-content\/uploads\/2015\/11\/aravaca-11.jpg\" class=\"attachment-large size-large\" alt=\"\" srcset=\"https:\/\/calderonbilbao.com\/wp-content\/uploads\/2015\/11\/aravaca-11.jpg 612w, https:\/\/calderonbilbao.com\/wp-content\/uploads\/2015\/11\/aravaca-11-150x150.jpg 150w, https:\/\/calderonbilbao.com\/wp-content\/uploads\/2015\/11\/aravaca-11-300x300.jpg 300w\" sizes=\"auto, (max-width: 612px) 100vw, 612px\" \/>\n\t\t\t<\/div><\/figure>\n\t\t<\/div>\n\n<div id='gallery-7' class='gallery galleryid-1134 gallery-columns-2 gallery-size-large'><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon portrait'>\n\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"511\" height=\"768\" src=\"https:\/\/calderonbilbao.com\/wp-content\/uploads\/2015\/11\/aravaca-12.jpg\" class=\"attachment-large size-large\" alt=\"\" srcset=\"https:\/\/calderonbilbao.com\/wp-content\/uploads\/2015\/11\/aravaca-12.jpg 511w, https:\/\/calderonbilbao.com\/wp-content\/uploads\/2015\/11\/aravaca-12-200x300.jpg 200w\" sizes=\"auto, (max-width: 511px) 100vw, 511px\" \/>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon portrait'>\n\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"511\" height=\"768\" src=\"https:\/\/calderonbilbao.com\/wp-content\/uploads\/2015\/11\/aravaca-13.jpg\" class=\"attachment-large size-large\" alt=\"\" srcset=\"https:\/\/calderonbilbao.com\/wp-content\/uploads\/2015\/11\/aravaca-13.jpg 511w, https:\/\/calderonbilbao.com\/wp-content\/uploads\/2015\/11\/aravaca-13-200x300.jpg 200w\" sizes=\"auto, (max-width: 511px) 100vw, 511px\" \/>\n\t\t\t<\/div><\/figure>\n\t\t<\/div>\n\n<div id='gallery-8' class='gallery galleryid-1134 gallery-columns-1 gallery-size-large'><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon portrait'>\n\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"672\" height=\"1024\" src=\"https:\/\/calderonbilbao.com\/wp-content\/uploads\/2015\/11\/aravaca-14-672x1024.jpg\" class=\"attachment-large size-large\" alt=\"\" srcset=\"https:\/\/calderonbilbao.com\/wp-content\/uploads\/2015\/11\/aravaca-14-672x1024.jpg 672w, https:\/\/calderonbilbao.com\/wp-content\/uploads\/2015\/11\/aravaca-14-197x300.jpg 197w, https:\/\/calderonbilbao.com\/wp-content\/uploads\/2015\/11\/aravaca-14-768x1170.jpg 768w, https:\/\/calderonbilbao.com\/wp-content\/uploads\/2015\/11\/aravaca-14-525x800.jpg 525w, https:\/\/calderonbilbao.com\/wp-content\/uploads\/2015\/11\/aravaca-14.jpg 985w\" sizes=\"auto, (max-width: 672px) 100vw, 672px\" \/>\n\t\t\t<\/div><\/figure>\n\t\t<\/div>\n\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":1,"featured_media":1005,"parent":0,"menu_order":140,"comment_status":"closed","ping_status":"closed","template":"page-horizontal.php","meta":{"footnotes":""},"class_list":["post-1134","page","type-page","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.3 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Aravaca - Calder\u00f3n Bilbao<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/calderonbilbao.com\/en\/aravaca\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Aravaca - Calder\u00f3n Bilbao\" \/>\n<meta property=\"og:url\" content=\"https:\/\/calderonbilbao.com\/en\/aravaca\/\" \/>\n<meta property=\"og:site_name\" content=\"Calder\u00f3n Bilbao\" \/>\n<meta property=\"article:modified_time\" content=\"2025-11-06T11:02:14+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/calderonbilbao.com\/wp-content\/uploads\/2015\/11\/aravaca-01.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1500\" \/>\n\t<meta property=\"og:image:height\" content=\"998\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/calderonbilbao.com\/en\/aravaca\/\",\"url\":\"https:\/\/calderonbilbao.com\/en\/aravaca\/\",\"name\":\"Aravaca - Calder\u00f3n Bilbao\",\"isPartOf\":{\"@id\":\"https:\/\/calderonbilbao.com\/en\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/calderonbilbao.com\/en\/aravaca\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/calderonbilbao.com\/en\/aravaca\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/calderonbilbao.com\/wp-content\/uploads\/2015\/11\/aravaca-01.jpg\",\"datePublished\":\"2015-11-25T09:46:56+00:00\",\"dateModified\":\"2025-11-06T11:02:14+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/calderonbilbao.com\/en\/aravaca\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/calderonbilbao.com\/en\/aravaca\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/calderonbilbao.com\/en\/aravaca\/#primaryimage\",\"url\":\"https:\/\/calderonbilbao.com\/wp-content\/uploads\/2015\/11\/aravaca-01.jpg\",\"contentUrl\":\"https:\/\/calderonbilbao.com\/wp-content\/uploads\/2015\/11\/aravaca-01.jpg\",\"width\":1500,\"height\":998},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/calderonbilbao.com\/en\/aravaca\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\/\/calderonbilbao.com\/en\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Aravaca\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/calderonbilbao.com\/en\/#website\",\"url\":\"https:\/\/calderonbilbao.com\/en\/\",\"name\":\"Calder\u00f3n Bilbao\",\"description\":\"Decoraci\u00f3n\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/calderonbilbao.com\/en\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Aravaca - Calder\u00f3n Bilbao","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/calderonbilbao.com\/en\/aravaca\/","og_locale":"en_US","og_type":"article","og_title":"Aravaca - Calder\u00f3n Bilbao","og_url":"https:\/\/calderonbilbao.com\/en\/aravaca\/","og_site_name":"Calder\u00f3n Bilbao","article_modified_time":"2025-11-06T11:02:14+00:00","og_image":[{"width":1500,"height":998,"url":"https:\/\/calderonbilbao.com\/wp-content\/uploads\/2015\/11\/aravaca-01.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/calderonbilbao.com\/en\/aravaca\/","url":"https:\/\/calderonbilbao.com\/en\/aravaca\/","name":"Aravaca - Calder\u00f3n Bilbao","isPartOf":{"@id":"https:\/\/calderonbilbao.com\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/calderonbilbao.com\/en\/aravaca\/#primaryimage"},"image":{"@id":"https:\/\/calderonbilbao.com\/en\/aravaca\/#primaryimage"},"thumbnailUrl":"https:\/\/calderonbilbao.com\/wp-content\/uploads\/2015\/11\/aravaca-01.jpg","datePublished":"2015-11-25T09:46:56+00:00","dateModified":"2025-11-06T11:02:14+00:00","breadcrumb":{"@id":"https:\/\/calderonbilbao.com\/en\/aravaca\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/calderonbilbao.com\/en\/aravaca\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/calderonbilbao.com\/en\/aravaca\/#primaryimage","url":"https:\/\/calderonbilbao.com\/wp-content\/uploads\/2015\/11\/aravaca-01.jpg","contentUrl":"https:\/\/calderonbilbao.com\/wp-content\/uploads\/2015\/11\/aravaca-01.jpg","width":1500,"height":998},{"@type":"BreadcrumbList","@id":"https:\/\/calderonbilbao.com\/en\/aravaca\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/calderonbilbao.com\/en\/"},{"@type":"ListItem","position":2,"name":"Aravaca"}]},{"@type":"WebSite","@id":"https:\/\/calderonbilbao.com\/en\/#website","url":"https:\/\/calderonbilbao.com\/en\/","name":"Calder\u00f3n Bilbao","description":"Decoraci\u00f3n","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/calderonbilbao.com\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"}]}},"_links":{"self":[{"href":"https:\/\/calderonbilbao.com\/en\/wp-json\/wp\/v2\/pages\/1134","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/calderonbilbao.com\/en\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/calderonbilbao.com\/en\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/calderonbilbao.com\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/calderonbilbao.com\/en\/wp-json\/wp\/v2\/comments?post=1134"}],"version-history":[{"count":1,"href":"https:\/\/calderonbilbao.com\/en\/wp-json\/wp\/v2\/pages\/1134\/revisions"}],"predecessor-version":[{"id":64284,"href":"https:\/\/calderonbilbao.com\/en\/wp-json\/wp\/v2\/pages\/1134\/revisions\/64284"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/calderonbilbao.com\/en\/wp-json\/wp\/v2\/media\/1005"}],"wp:attachment":[{"href":"https:\/\/calderonbilbao.com\/en\/wp-json\/wp\/v2\/media?parent=1134"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}